{"id":129,"count":7,"description":"","link":"http:\/\/dixonarchive.com\/motorblog\/category\/jeep\/cherokee\/","name":"Cherokee","slug":"cherokee","taxonomy":"category","parent":31,"meta":[],"_links":{"self":[{"href":"http:\/\/dixonarchive.com\/motorblog\/wp-json\/wp\/v2\/categories\/129","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/dixonarchive.com\/motorblog\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"http:\/\/dixonarchive.com\/motorblog\/wp-json\/wp\/v2\/taxonomies\/category"}],"up":[{"embeddable":true,"href":"http:\/\/dixonarchive.com\/motorblog\/wp-json\/wp\/v2\/categories\/31"}],"wp:post_type":[{"href":"http:\/\/dixonarchive.com\/motorblog\/wp-json\/wp\/v2\/posts?categories=129"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}