{"id":31,"count":34,"description":"","link":"http:\/\/dixonarchive.com\/motorblog\/category\/jeep\/","name":"Jeep","slug":"jeep","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"http:\/\/dixonarchive.com\/motorblog\/wp-json\/wp\/v2\/categories\/31","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/dixonarchive.com\/motorblog\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"http:\/\/dixonarchive.com\/motorblog\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"http:\/\/dixonarchive.com\/motorblog\/wp-json\/wp\/v2\/posts?categories=31"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}