{"id":532,"count":1,"description":"","link":"http:\/\/dixonarchive.com\/motorblog\/category\/subaru\/levorg\/","name":"Levorg","slug":"levorg","taxonomy":"category","parent":54,"meta":[],"_links":{"self":[{"href":"http:\/\/dixonarchive.com\/motorblog\/wp-json\/wp\/v2\/categories\/532","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/dixonarchive.com\/motorblog\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"http:\/\/dixonarchive.com\/motorblog\/wp-json\/wp\/v2\/taxonomies\/category"}],"up":[{"embeddable":true,"href":"http:\/\/dixonarchive.com\/motorblog\/wp-json\/wp\/v2\/categories\/54"}],"wp:post_type":[{"href":"http:\/\/dixonarchive.com\/motorblog\/wp-json\/wp\/v2\/posts?categories=532"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}